{"id":31328,"date":"2020-10-10T11:08:04","date_gmt":"2020-10-10T02:08:04","guid":{"rendered":"https:\/\/www.fgautron.com\/weblog\/?p=31328"},"modified":"2020-10-10T11:08:29","modified_gmt":"2020-10-10T02:08:29","slug":"to-the-endless-sea-of-light","status":"publish","type":"post","link":"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/10\/10\/to-the-endless-sea-of-light\/","title":{"rendered":"to the endless sea of light"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31329\" data-permalink=\"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/10\/10\/to-the-endless-sea-of-light\/img_4320wm\/\" data-orig-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4320wm.jpg\" data-orig-size=\"2000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;7.1&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1601724644&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;38&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.005&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4320wm\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4320wm-700x467.jpg\" src=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4320wm.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"aligncenter size-full wp-image-31329\" srcset=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4320wm.jpg 2000w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4320wm-300x200.jpg 300w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4320wm-700x467.jpg 700w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4320wm-1536x1024.jpg 1536w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4320wm-800x533.jpg 800w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31330\" data-permalink=\"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/10\/10\/to-the-endless-sea-of-light\/img_4314wm\/\" data-orig-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4314wm.jpg\" data-orig-size=\"2000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1601724512&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;24&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4314wm\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4314wm-700x467.jpg\" src=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4314wm.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"aligncenter size-full wp-image-31330\" srcset=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4314wm.jpg 2000w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4314wm-300x200.jpg 300w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4314wm-700x467.jpg 700w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4314wm-1536x1024.jpg 1536w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4314wm-800x533.jpg 800w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31331\" data-permalink=\"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/10\/10\/to-the-endless-sea-of-light\/img_4316wm\/\" data-orig-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4316wm.jpg\" data-orig-size=\"2000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;10&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1601724543&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;20&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.004&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4316wm\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4316wm-700x467.jpg\" src=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4316wm.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"aligncenter size-full wp-image-31331\" srcset=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4316wm.jpg 2000w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4316wm-300x200.jpg 300w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4316wm-700x467.jpg 700w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4316wm-1536x1024.jpg 1536w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4316wm-800x533.jpg 800w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31332\" data-permalink=\"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/10\/10\/to-the-endless-sea-of-light\/img_4312wm\/\" data-orig-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4312wm.jpg\" data-orig-size=\"2000,1333\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;Canon EOS 50D&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1601724231&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;40&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.00625&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_4312wm\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4312wm-700x467.jpg\" src=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/IMG_4312wm.jpg\" alt=\"\" width=\"2000\" height=\"1333\" class=\"aligncenter size-full wp-image-31332\" srcset=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4312wm.jpg 2000w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4312wm-300x200.jpg 300w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4312wm-700x467.jpg 700w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4312wm-1536x1024.jpg 1536w, https:\/\/www.fgautron.com\/weblog\/wp-content\/IMG_4312wm-800x533.jpg 800w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/p>\n<p>Le but de ma promenade du Samedi matin \u00e9tait d\u2019aller marcher jusqu\u2019\u00e0 Sangenjaya, mais je n\u2019irais que jusqu\u2019\u00e0 Shinsen car je me laisse distraire en route par le paysage urbain comme toujours. Apr\u00e8s toutes ces ann\u00e9es \u00e0 prendre des photographies dans les rues de Tokyo, je suis surpris moi-m\u00eame de ne pas en avoir marre. J\u2019ai m\u00eame l\u2019impression d\u2019en avoir de plus en plus besoin. Un des int\u00e9r\u00eats principal pour moi de cette ville, outre son architecture chaotique, est la pr\u00e9sence de terrains vallon\u00e9s. Les pentes dans la ville font tout l\u2019int\u00e9r\u00eat du paysage urbain et j\u2019ai tendance \u00e0 m\u2019ennuyer quand le terrain est plat. La colline me donne envie d\u2019aller d\u00e9couvrir le myst\u00e8re qui se cache derri\u00e8re. Lorsqu\u2019on atteint un sommet, on a rarement une vue d\u00e9gag\u00e9e, mais plut\u00f4t une vue encombr\u00e9e comme sur la deuxi\u00e8me photographie avec une multitude de couches superpos\u00e9es d\u2019immeubles en toile de fond. Les maisons basses et les points de verdure \u00e0 l\u2019avant nous rappellent que nous sommes dans une zone r\u00e9sidentielle. Les pentes dans la ville m\u2019assure que l\u2019architecture et l\u2019organisation urbaine seront compliqu\u00e9es et c\u2019est ce que je recherche dans mes promenades continuelles quand le temps me le permet (au deux sens du terme). Je suis s\u00fbr que cette recherche de la complexit\u00e9 et densit\u00e9 urbaine a \u00e0 voir avec ma peur du vide, tout comme le besoin d\u2019\u00e9crire sans arr\u00eats sur ces pages, comme d\u2019autres ne peuvent pas laisser d\u2019espaces blancs dans une conversation. En fait, je souhaitais passer par Shinsen, car je voulais revoir le passage \u00e0 niveau de la premi\u00e8re photographie car cet endroit est assez photog\u00e9nique. Je l\u2019ai m\u00eame d\u00e9j\u00e0 vu utilis\u00e9 pour des <a href=\"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/01\/08\/envol-du-corbeau\/https:\/\/www.fgautron.com\/weblog\/archives\/2020\/01\/08\/envol-du-corbeau\/\">photos promotionnels<\/a> de groupes de musique. J\u2019attends que le train passe en sortant du tunnel. La robe de la dame vole un peu, pouss\u00e9e par le courant d\u2019air. L\u2019angle n\u2019est pas id\u00e9al car le mur de la gare sur la droite me g\u00e8ne un peu. La dame avec la poussette me regardait un bref instant prendre des photos alors j\u2019ai pr\u00e9f\u00e9r\u00e9 rester un peu en retrait. En fait je voulais \u00e9galement pendre le restaurant color\u00e9 tha\u00ef sur la gauche en photo, mais je ne suis pas du genre \u00e0 attendre sur place que la situation devienne id\u00e9ale pour une photo. J\u2019ai quand m\u00eame un peu attendu que le train arrive en gare.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"31336\" data-permalink=\"https:\/\/www.fgautron.com\/weblog\/archives\/2020\/10\/10\/to-the-endless-sea-of-light\/smany-illuminate\/\" data-orig-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/smany-illuminate.jpg\" data-orig-size=\"600,592\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"smany-illuminate\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/smany-illuminate.jpg\" src=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/\/smany-illuminate.jpg\" alt=\"\" width=\"600\" height=\"592\" class=\"aligncenter size-full wp-image-31336\" srcset=\"https:\/\/www.fgautron.com\/weblog\/wp-content\/smany-illuminate.jpg 600w, https:\/\/www.fgautron.com\/weblog\/wp-content\/smany-illuminate-300x296.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>La musique de <a href=\"https:\/\/twitter.com\/smany000\">Smany<\/a> sur son album <a href=\"https:\/\/virginbabylonrecords.bandcamp.com\/album\/illuminate\">Illuminate<\/a> est pour moi une autre tr\u00e8s belle d\u00e9couverte ces derni\u00e8res semaines. Je suis en ce moment dans une phase d\u2019\u00e9coute de musiques obscures (qui ne va pas s\u2019arranger avec un des prochains billets, je pr\u00e9viens). La musique de Juri Toyoda, alias Smany, est tr\u00e8s m\u00e9lodique, sombre mais parsem\u00e9e de points lumineux comme l\u2019indique d\u2019ailleurs le titre de l\u2019album Illuminate. Les cordes du premier morceau de l\u2019album <a href=\"https:\/\/www.youtube.com\/watch?v=hrgl3ucLXEU\">dye the darkness<\/a> me donne tout de suite des frissons, surtout lorsque le piano fait son apparition. Cette musique est vraiment tr\u00e8s belle et la voix de Smany tr\u00e8s pr\u00e9sente, parfois pr\u00e9dominante et intimiste sur certains morceaux. Les morceaux prennent leur temps et sont tr\u00e8s d\u00e9licats. Il y a une m\u00e9lancolie certaine qui se d\u00e9gage de cette musique. Le morceau <a href=\"https:\/\/virginbabylonrecords.bandcamp.com\/track\/blurry-moon\">Blurry Moon<\/a> est magnifique m\u00e9langeant une partition symphonique, des surimpressions \u00e9lectroniques que je qualifierais de spectrales, et la voix \u00e0 la fois fragile et puissante de Smany. Ce titre correspond bien \u00e0 l\u2019image g\u00e9n\u00e9rale de l\u2019album, une musique remplie d\u2019obscurit\u00e9 mais \u00e9clair\u00e9e par instants par la lumi\u00e8re \u00e9ph\u00e9m\u00e8re de la lune. Avec le cinqui\u00e8me morceau intitul\u00e9 <a href=\"https:\/\/www.youtube.com\/watch?v=nriP8996TtI\">usagi<\/a>, j\u2019ai m\u00eame le sentiment que la la lumi\u00e8re lunaire est le th\u00e8me central de cet album (les japonais voit une image de lapin dans la lune). Ce morceau usagi est peut \u00eatre mon pr\u00e9f\u00e9r\u00e9, j\u2019adore les distorsions sonores au d\u00e9but et ponctuant le morceau, la voix (encore) de Smany tr\u00e8s proche de l\u2019auditeur et son air de conte enfantin. Il y a quelques morceaux un peu plus in\u00e9gaux mais qui ne nuisent pas \u00e0 l\u2019ambiance g\u00e9n\u00e9rale de l\u2019album et viennent s\u2019y fondre. Et il y a le morceau <a href=\"https:\/\/www.youtube.com\/watch?v=dwfY-abVAhE\">fall<\/a> et, l\u00e0 encore, la puissance des cordes qui nous envahissent (il faut \u00e9couter assez fort aux \u00e9couteurs). La voix de Smany vient s\u2019y noyer, parfois en murmures, mais ne perd pas pied. Le huiti\u00e8me morceau <a href=\"https:\/\/www.youtube.com\/watch?v=X3r_TSdnY-s\">Himitsu<\/a> en collaboration avec World\u2019s End Girlfriend (dont j\u2019avais d\u00e9j\u00e0 un peu parl\u00e9 <a href=\"https:\/\/www.fgautron.com\/weblog\/archives\/2018\/09\/09\/\u6c38\u9060\u306e\u9580\/\">pr\u00e9c\u00e9demment<\/a>) est \u00e9galement remarquable et apporte quelques nouveaux rayons de lumi\u00e8re bienvenus. L\u2019album se termine avec le bien nomm\u00e9 <a href=\"https:\/\/virginbabylonrecords.bandcamp.com\/track\/over\">over<\/a> qui a la particularit\u00e9 de se conclure sur des sons sons \u00e9lectroniques en distortion qui me rappellent un peu Aphex Twin. On n\u2019atteint pas ici l\u2019aspect incisif d\u2019Aphex Twin, mais ce petit passage en fin d\u2019album avec une coupure abrupte est tr\u00e8s int\u00e9ressante. Illuminate est sorti le 26 Septembre 2020 sur le label Virgin Babylon Records et est disponible sur <a href=\"https:\/\/virginbabylonrecords.bandcamp.com\/album\/illuminate\">Bandcamp<\/a>. Je l&rsquo;ai achet\u00e9 le jour o\u00f9 Bandcamp levait son pourcentage au profit des artistes. C&rsquo;est une op\u00e9ration que Bandcamp poursuit une fois par mois pendant la crise sanitaire, ce que ne font pas d&rsquo;autres plateformes \u00e0 ma connaissance. En commentaire sur la page de l&rsquo;album, Smany indique qu&rsquo;elle voulait d\u00e9crire le <em>vide<\/em> \u00e0 travers cet album (\u63cf\u304d\u305f\u304b\u3063\u305f\u306e\u306f&rsquo;<em>\u7121<\/em>&lsquo;), mais un vide qui se remplit d&rsquo;une <em>lumi\u00e8re<\/em> \u00e9ph\u00e9m\u00e8re (\u4f5c\u54c1\u3092\u4f5c\u308a\u4e0a\u3052\u3066\u3044\u304f\u5148\u306b\u898b\u3048\u305f\u666f\u8272\u306f\u3001\u511a\u304f\u3082\u7f8e\u3057\u3044&rsquo;<em>\u5149<\/em>&lsquo;\u3067\u3057\u305f\u3002). Je ne ressens pourtant pas de vide dans cette musique mais je comprends qu\u2019il nous parle principalement de la perception d\u2019une lumi\u00e8re. Je la ressens tr\u00e8s bien ici comme celle que j\u2019essaie de percevoir \u00e0 travers l\u2019appareil photo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le but de ma promenade du Samedi matin \u00e9tait d\u2019aller marcher jusqu\u2019\u00e0 Sangenjaya, mais je n\u2019irais que jusqu\u2019\u00e0 Shinsen car je me laisse distraire en route par le paysage urbain comme toujours. Apr\u00e8s toutes ces ann\u00e9es \u00e0 prendre des photographies dans les rues de Tokyo, je suis surpris moi-m\u00eame de ne pas en avoir marre&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"to the endless sea of light","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4,3],"tags":[1896,1895],"class_list":["post-31328","post","type-post","status-publish","format-standard","hentry","category-musiques","category-tokyo","tag-shinsen","tag-smany"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/posts\/31328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/comments?post=31328"}],"version-history":[{"count":14,"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/posts\/31328\/revisions"}],"predecessor-version":[{"id":31363,"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/posts\/31328\/revisions\/31363"}],"wp:attachment":[{"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/media?parent=31328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/categories?post=31328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fgautron.com\/weblog\/wp-json\/wp\/v2\/tags?post=31328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}